{"id":23688,"date":"2025-12-10T19:49:56","date_gmt":"2025-12-10T19:49:56","guid":{"rendered":"https:\/\/endowment.org\/?post_type=news&#038;p=23688"},"modified":"2025-12-11T20:41:04","modified_gmt":"2025-12-11T20:41:04","slug":"nuevo-fondo-de-legado-de-flores-de-la-familia-mccarthy","status":"publish","type":"news","link":"https:\/\/endowment.org\/es\/news\/new-mccarthy-family-flowers-legacy-fund","title":{"rendered":"El nuevo Fondo de Legado de la Familia McCarthy-Family Flowers apoya a los floristas minoristas multigeneracionales"},"content":{"rendered":"<figure class=\"wp-block-image alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png\" alt=\"\" class=\"wp-image-20291\" style=\"width:247px;height:auto\" srcset=\"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png 1024w, https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-300x300.png 300w, https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-150x150.png 150w, https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-768x768.png 768w, https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1536x1536.png 1536w, https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-2048x2048.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nos enorgullece anunciar la creaci\u00f3n de la <strong><a href=\"https:\/\/endowment.org\/es\/conceder\/fondo-legado-de-flores-de-la-familia-mccarthy\/\">Fondo de Legado de Flores de la Familia McCarthy<\/a>,<\/strong> un nuevo fondo establecido conjuntamente con la familia McCarthy, propietaria de Family Flowers, dentro de la Fundaci\u00f3n para impulsar y empoderar a los floristas minoristas multigeneracionales. Este nuevo fondo celebra a las florister\u00edas familiares que durante mucho tiempo han servido como pilares de sus comunidades, aportando tradici\u00f3n, creatividad y una conexi\u00f3n sincera a la industria floral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Establecido a trav\u00e9s de una generosa donaci\u00f3n plurianual de la Familia McCarthy, el fondo honra el legado perdurable de los floristas minoristas multigeneracionales. Durante d\u00e9cadas, las florister\u00edas familiares han fortalecido a sus comunidades con creatividad y servicio personalizado. A trav\u00e9s de becas anuales de viaje educativo que apoyan el desarrollo del liderazgo y la sostenibilidad comercial a largo plazo, esto ayudar\u00e1 a garantizar que estos negocios sigan prosperando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cGeneraciones de floristas familiares han construido esta industria a trav\u00e9s del trabajo duro, la dedicaci\u00f3n y el coraz\u00f3n, pero la transici\u00f3n de una generaci\u00f3n a la siguiente a menudo se pasa por alto. Como florista de cuarta generaci\u00f3n, estoy orgulloso de que podamos ayudar a equipar a los futuros l\u00edderes florales con las herramientas, la educaci\u00f3n y la inspiraci\u00f3n necesarias para continuar nuestro oficio durante los a\u00f1os venideros,\u201d<\/strong>&nbsp;dijo Kevin McCarthy, propietario y director ejecutivo de Family Flowers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada a\u00f1o, el Fondo \u00abMcCarthy-Family Flowers Legacy\u00bb conceder\u00e1 una beca de viaje con fines formativos de hasta $1.000 para ayudar a las florister\u00edas minoristas tradicionales de gesti\u00f3n familiar a superar las barreras que les impiden participar o asistir a eventos de desarrollo profesional presenciales, incluidas las convenciones regionales, estatales o nacionales. Estas oportunidades refuerzan las habilidades empresariales, ampl\u00edan las redes del sector, fomentan la innovaci\u00f3n y respaldan la planificaci\u00f3n de la sucesi\u00f3n, fundamental para las empresas que se encuentran en proceso de transici\u00f3n entre generaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qui\u00e9n puede solicitarlo<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las solicitudes estar\u00e1n abiertas para propietarios o herederos de la pr\u00f3xima generaci\u00f3n de florister\u00edas f\u00edsicas. Aunque se anima a todos los floristas a postularse, se dar\u00e1 prioridad a aquellos que representen a empresas familiares multigeneracionales, como l\u00edderes de segunda o tercera generaci\u00f3n que contin\u00faan el legado de su familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fondos se proporcionan despu\u00e9s de presentar a AFE la prueba de inscripci\u00f3n y el pago. La fecha l\u00edmite de solicitud de cada a\u00f1o ser\u00e1 el 1 de octubre, y los fondos respaldar\u00e1n los viajes para el a\u00f1o calendario siguiente. <strong>Se har\u00e1 un anuncio cuando las solicitudes inaugurales est\u00e9n oficialmente abiertas para esta subvenci\u00f3n.&nbsp;<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Honrando un legado familiar: La historia de Family Flowers<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"308\" src=\"https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/01stLocation.avif\" alt=\"\" class=\"wp-image-23701\" style=\"width:411px;height:auto\" srcset=\"https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/01stLocation.avif 450w, https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/01stLocation-300x205.avif 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso de la familia McCarthy con las florister\u00edas locales, la tradici\u00f3n de la industria y la conexi\u00f3n con la comunidad es profundo. Family Flowers comenz\u00f3 en 1952, cuando John \u201cBud\u201d McCarthy abri\u00f3 la tienda Bud McCarthy\u2019s BOKAY cerca de Scranton, Pensilvania. Su creencia era simple pero profunda: las flores dicen lo que las palabras solas no pueden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esa \u00fanica tienda surgi\u00f3 una orgullosa empresa familiar de varias generaciones que contin\u00faa el legado de queridos floristas locales en 10 estados, sin perder sus ra\u00edces en el arte hecho a mano y el servicio sincero. Durante m\u00e1s de 70 a\u00f1os, la familia McCarthy ha estado creando arreglos florales dise\u00f1ados y entregados a mano que celebran los momentos m\u00e1s importantes de la vida y ofrecen consuelo durante los m\u00e1s dif\u00edciles.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family.webp\" alt=\"\" class=\"wp-image-23689\" style=\"aspect-ratio:2.000059640961412;width:369px;height:auto\" srcset=\"https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family.webp 1000w, https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family-300x150.webp 300w, https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family-768x384.webp 768w, https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family-540x270.webp 540w, https:\/\/endowment.org\/wp-content\/uploads\/2025\/12\/McCarthy-Family-900x450.webp 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La familia McCarthy sigue comprometida en apoyar a las florister\u00edas locales mientras las ayuda a adaptarse y prosperar en un panorama minorista que cambia r\u00e1pidamente. Ese compromiso inspir\u00f3 la creaci\u00f3n del Fondo de Legado de Flores de la Familia McCarthy: una inversi\u00f3n significativa en el futuro de la florister\u00eda familiar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este nuevo fondo se suma a m\u00e1s de 70 Fondos Nominados administrados por la AFE, cada uno dedicado a fortalecer diferentes pilares de la industria floral, desde la investigaci\u00f3n y las becas hasta las pasant\u00edas, la educaci\u00f3n y los programas comunitarios. Juntos, estos fondos crean una red de apoyo poderosa que sostiene el \u00e9xito a largo plazo de la industria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos honra asociarnos con la familia McCarthy en este importante esfuerzo y esperamos empoderar a las florer\u00edas familiares en todo el pa\u00eds durante muchos a\u00f1os m\u00e1s.<\/p>","protected":false},"template":"","news-categories":[53,31,29,41],"class_list":["post-23688","news","type-news","status-publish","hentry","news-categories-grants","news-categories-latest-news","news-categories-news","news-categories-florist-event"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists - American Floral Endowment<\/title>\n<meta name=\"description\" content=\"We are proud to announce the creation of the McCarthy-Family Flowers Legacy Fund, a new fund jointly established with the McCarthy Family, owners of Family Flowers, within the Endowment to uplift and empower multi-generational retail florists.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endowment.org\/es\/noticias\/nuevo-fondo-de-legado-de-flores-de-la-familia-mccarthy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists - American Floral Endowment\" \/>\n<meta property=\"og:description\" content=\"We are proud to announce the creation of the McCarthy-Family Flowers Legacy Fund, a new fund jointly established with the McCarthy Family, owners of Family Flowers, within the Endowment to uplift and empower multi-generational retail florists.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endowment.org\/es\/noticias\/nuevo-fondo-de-legado-de-flores-de-la-familia-mccarthy\/\" \/>\n<meta property=\"og:site_name\" content=\"American Floral Endowment\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T20:41:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/\",\"url\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/\",\"name\":\"New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists - American Floral Endowment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endowment.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endowment.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/familyflowers-1024x1024.png\",\"datePublished\":\"2025-12-10T19:49:56+00:00\",\"dateModified\":\"2025-12-11T20:41:04+00:00\",\"description\":\"We are proud to announce the creation of the McCarthy-Family Flowers Legacy Fund, a new fund jointly established with the McCarthy Family, owners of Family Flowers, within the Endowment to uplift and empower multi-generational retail florists.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/endowment.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/familyflowers-1024x1024.png\",\"contentUrl\":\"https:\\\/\\\/endowment.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/familyflowers-1024x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endowment.org\\\/news\\\/new-mccarthy-family-flowers-legacy-fund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/endowment.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endowment.org\\\/#website\",\"url\":\"https:\\\/\\\/endowment.org\\\/\",\"name\":\"American Floral Endowment\",\"description\":\"Funding the Future of Floriculture\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endowment.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo Fondo Legado de Flores de la Familia McCarthy Apoya a Floristas Minoristas Multigeneracionales - American Floral Endowment","description":"Nos enorgullece anunciar la creaci\u00f3n del Fondo Legado de Flores de la Familia McCarthy (McCarthy-Family Flowers Legacy Fund), un nuevo fondo establecido conjuntamente con la Familia McCarthy, propietaria de Family Flowers, dentro de la Fundaci\u00f3n (Endowment) para impulsar y empoderar a los floristas minoristas multigeneracionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endowment.org\/es\/noticias\/nuevo-fondo-de-legado-de-flores-de-la-familia-mccarthy\/","og_locale":"es_ES","og_type":"article","og_title":"New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists - American Floral Endowment","og_description":"We are proud to announce the creation of the McCarthy-Family Flowers Legacy Fund, a new fund jointly established with the McCarthy Family, owners of Family Flowers, within the Endowment to uplift and empower multi-generational retail florists.","og_url":"https:\/\/endowment.org\/es\/noticias\/nuevo-fondo-de-legado-de-flores-de-la-familia-mccarthy\/","og_site_name":"American Floral Endowment","article_modified_time":"2025-12-11T20:41:04+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/","url":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/","name":"Nuevo Fondo Legado de Flores de la Familia McCarthy Apoya a Floristas Minoristas Multigeneracionales - American Floral Endowment","isPartOf":{"@id":"https:\/\/endowment.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/#primaryimage"},"image":{"@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/#primaryimage"},"thumbnailUrl":"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png","datePublished":"2025-12-10T19:49:56+00:00","dateModified":"2025-12-11T20:41:04+00:00","description":"Nos enorgullece anunciar la creaci\u00f3n del Fondo Legado de Flores de la Familia McCarthy (McCarthy-Family Flowers Legacy Fund), un nuevo fondo establecido conjuntamente con la Familia McCarthy, propietaria de Family Flowers, dentro de la Fundaci\u00f3n (Endowment) para impulsar y empoderar a los floristas minoristas multigeneracionales.","breadcrumb":{"@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/#primaryimage","url":"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png","contentUrl":"https:\/\/endowment.org\/wp-content\/uploads\/2024\/05\/familyflowers-1024x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/endowment.org\/news\/new-mccarthy-family-flowers-legacy-fund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/endowment.org\/"},{"@type":"ListItem","position":2,"name":"New McCarthy-Family Flowers Legacy Fund Supports Multi-Generational Retail Florists"}]},{"@type":"WebSite","@id":"https:\/\/endowment.org\/#website","url":"https:\/\/endowment.org\/","name":"Fundaci\u00f3n Floral Americana","description":"Financiaci\u00f3n del futuro de la floricultura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endowment.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/news\/23688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":8,"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/news\/23688\/revisions"}],"predecessor-version":[{"id":23738,"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/news\/23688\/revisions\/23738"}],"wp:attachment":[{"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/media?parent=23688"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/endowment.org\/es\/wp-json\/wp\/v2\/news-categories?post=23688"}],"curies":[{"name":"bien jugado","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}